{"id":62405,"date":"2026-01-09T15:15:04","date_gmt":"2026-01-09T15:15:04","guid":{"rendered":"https:\/\/wordpress.bottle-up.com\/?page_id=62405"},"modified":"2026-01-25T22:11:12","modified_gmt":"2026-01-25T22:11:12","slug":"wedding-planner","status":"publish","type":"page","link":"https:\/\/bo2.x-brain.it\/it\/wedding-planner\/","title":{"rendered":"Wedding Planner"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"62405\" class=\"elementor elementor-62405\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d10616a header-cat e-con-full e-flex e-con e-parent\" data-id=\"d10616a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-23d710e e-con-full e-flex e-con e-child\" data-id=\"23d710e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03ec69e nomb-last-p subtitle-l elementor-widget elementor-widget-text-editor\" data-id=\"03ec69e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wedding Planner<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74650ca elementor-widget__width-initial h1-cat elementor-widget elementor-widget-printec_animated-headline\" data-id=\"74650ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"printec_animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <h1  class=\"elementor-headline\">\n                    <span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Bottiglie personalizzate: <\/span>\n                <span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n                    <span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">servizio Wedding Planner<\/span>\n        \t\t<\/span>\n                <\/h1>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25b428a elementor-widget__width-initial mobile-color-black elementor-widget elementor-widget-text-editor\" data-id=\"25b428a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Sei un Wedding Planner? Stupisci i tuoi sposi con le bottiglie personalizzate come bomboniere gastronomiche per il matrimonio o in abbinamento al menu<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04bbd1b e-con-full container-btn e-flex e-con e-child\" data-id=\"04bbd1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8caa36 elementor-mobile_extra-align-center effect-icon-yes button-purp elementor-button-default elementor-widget elementor-widget-button\" data-id=\"c8caa36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#chiediciunpreventivo\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"printec-icon- printec-icon-right-arrow\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi un preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e364c9d elementor-mobile_extra-align-center effect-icon-yes btn-border-1 elementor-button-default elementor-widget elementor-widget-button\" data-id=\"e364c9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/contatti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"printec-icon- printec-icon-right-arrow\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Diventa un nostro partner<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3785f9 pt-xl title-c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3785f9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea650e2\" data-id=\"ea650e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ceaa86 h2-bic-cat elementor-widget elementor-widget-xbtitle\" data-id=\"0ceaa86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"xbtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t    <div class=\"xb-title-widget\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"xb-title\">Crea in pochi click la tua <span>bottiglia personalizzata<\/span> per il tuo regalo <span>speciale<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t    <\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13e71bc product-2-rows elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13e71bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cdedf60\" data-id=\"cdedf60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-0ad81ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ad81ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f93ff67 pb-xl\" data-id=\"f93ff67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ce5fb4 mobile-switcher-style-product-yes arrow-style-1 dot-style-1 elementor-widget elementor-widget-xbproducts\" data-id=\"4ce5fb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"xbproducts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-4  columns-tablet-2 columns-mobile-2\"><ul class=\"products columns-4\"><li class=\"product-style-default product type-product post-29382 status-publish first instock product_cat-matrimoni product_tag-big-format product_tag-wooden-box has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n    <div class=\"product-block\">\n        <div class=\"content-product-imagin\"><\/div>\n        <div class=\"product-transition\">\n            <div class=\"product-image image-main\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-64fb34f6402100.74801477.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"N\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-64fb34f6402100.74801477.jpeg 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-64fb34f6402100.74801477-300x300.jpeg 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-64fb34f6402100.74801477-768x768.jpeg 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-64fb34f6402100.74801477-450x450.jpeg 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-64fb34f6402100.74801477-100x100.jpeg 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-64fb34f6402100.74801477-50x50.jpeg 50w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-64fb34f6402100.74801477-460x460.jpeg 460w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/div>                                                <div class=\"group-action\">\n                <div class=\"shop-action vertical\">\n                                    <\/div>\n            <\/div>\n            <a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/scatola-legno-bottiglia-vino-magnum-1-50-matrimonio-amore-vince-su-tutto\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            <\/a>        <\/div>\n        <div class=\"product-caption\">\n            <h3 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/scatola-legno-bottiglia-vino-magnum-1-50-matrimonio-amore-vince-su-tutto\/\">Scatola in legno 1 bottiglia MAGNUM 1,5 L &#8211; L&#8217;amore vince su tutto<\/a><\/h3>            \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>19,88<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n            <div class=\"product-caption-bottom\">\n                <a href=\"\/it\/wp-json\/wp\/v2\/pages\/62405?add-to-cart=29382\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29382\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"29382\" data-product_sku=\"PR928BOM984BO\" aria-label=\"Aggiungi al carrello: &quot;Scatola in legno 1 bottiglia MAGNUM 1,5 L - L&#039;amore vince su tutto&quot;\" rel=\"nofollow\" data-success_message=\"&quot;Scatola in legno 1 bottiglia MAGNUM 1,5 L - L&#039;amore vince su tutto&quot; \u00e8 stato aggiunto al tuo carrello\">Aggiungi al carrello<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29382\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li>\n<li class=\"product-style-default product type-product post-29284 status-publish instock product_cat-matrimoni product_tag-wooden-box has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n    <div class=\"product-block\">\n        <div class=\"content-product-imagin\"><\/div>\n        <div class=\"product-transition\">\n            <div class=\"product-image image-main\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6478999c0de014.22733685.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"N\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6478999c0de014.22733685.jpeg 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6478999c0de014.22733685-300x300.jpeg 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6478999c0de014.22733685-768x768.jpeg 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6478999c0de014.22733685-450x450.jpeg 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6478999c0de014.22733685-100x100.jpeg 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6478999c0de014.22733685-50x50.jpeg 50w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6478999c0de014.22733685-460x460.jpeg 460w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/div>                                                <div class=\"group-action\">\n                <div class=\"shop-action vertical\">\n                                    <\/div>\n            <\/div>\n            <a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/scatola-legno-bottiglia-vino-standard-075-matrimonio-amore-vince-su-tutto\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            <\/a>        <\/div>\n        <div class=\"product-caption\">\n            <h3 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/scatola-legno-bottiglia-vino-standard-075-matrimonio-amore-vince-su-tutto\/\">Scatola in legno 1 bottiglia 0,75 L &#8211; L&#8217;amore vince su tutto<\/a><\/h3>            \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>16,90<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n            <div class=\"product-caption-bottom\">\n                <a href=\"\/it\/wp-json\/wp\/v2\/pages\/62405?add-to-cart=29284\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29284\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"29284\" data-product_sku=\"PR796BOM951BO\" aria-label=\"Aggiungi al carrello: &quot;Scatola in legno 1 bottiglia 0,75 L - L&#039;amore vince su tutto&quot;\" rel=\"nofollow\" data-success_message=\"&quot;Scatola in legno 1 bottiglia 0,75 L - L&#039;amore vince su tutto&quot; \u00e8 stato aggiunto al tuo carrello\">Aggiungi al carrello<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29284\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li>\n<li class=\"product-style-default product type-product post-29242 status-publish instock product_cat-matrimoni product_tag-sweet has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n    <div class=\"product-block\">\n        <div class=\"content-product-imagin\"><\/div>\n        <div class=\"product-transition\">\n            <div class=\"product-image image-main\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d5625ef5be7.16320963.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"N\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d5625ef5be7.16320963.jpeg 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d5625ef5be7.16320963-300x300.jpeg 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d5625ef5be7.16320963-768x768.jpeg 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d5625ef5be7.16320963-450x450.jpeg 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d5625ef5be7.16320963-100x100.jpeg 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d5625ef5be7.16320963-50x50.jpeg 50w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d5625ef5be7.16320963-460x460.jpeg 460w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/div>            \n\t<span class=\"onsale\">10% DI SCONTO<\/span>\n\t                                    <div class=\"group-action\">\n                <div class=\"shop-action vertical\">\n                                    <\/div>\n            <\/div>\n            <a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/bomboniere-miele-matrimonio-etichetta-personalizzata-oggi-sposi-fiori-vasetto-250-g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            <\/a>        <\/div>\n        <div class=\"product-caption\">\n            <h3 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/bomboniere-miele-matrimonio-etichetta-personalizzata-oggi-sposi-fiori-vasetto-250-g\/\">24 Bomboniere miele matrimonio &#8211; vasetto miele millefiori 250g.<\/a><\/h3>            \n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>254,88<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Il prezzo originale era: 254,88&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>229,44<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Il prezzo attuale \u00e8: 229,44&euro;.<\/span><\/span>\n            <div class=\"product-caption-bottom\">\n                <a class=\"button product_type_simple add_to_cart_button button-reverse reverse\" href=\"https:\/\/bo2.x-brain.it\/en\/configurator\/#\/?id_store_products=755&id_woocommerce=29242\">Personalizza<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29242\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li>\n<li class=\"product-style-default product type-product post-29239 status-publish last instock product_cat-matrimoni product_tag-sweet has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n    <div class=\"product-block\">\n        <div class=\"content-product-imagin\"><\/div>\n        <div class=\"product-transition\">\n            <div class=\"product-image image-main\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d4f57c09186.46093782.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"N\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d4f57c09186.46093782.jpeg 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d4f57c09186.46093782-300x300.jpeg 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d4f57c09186.46093782-768x768.jpeg 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d4f57c09186.46093782-450x450.jpeg 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d4f57c09186.46093782-100x100.jpeg 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d4f57c09186.46093782-50x50.jpeg 50w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642d4f57c09186.46093782-460x460.jpeg 460w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/div>            \n\t<span class=\"onsale\">10% DI SCONTO<\/span>\n\t                                    <div class=\"group-action\">\n                <div class=\"shop-action vertical\">\n                                    <\/div>\n            <\/div>\n            <a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/bomboniere-miele-matrimonio-etichetta-personalizzata-sposi-cartoon-millefiori-135-g\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            <\/a>        <\/div>\n        <div class=\"product-caption\">\n            <h3 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/bomboniere-miele-matrimonio-etichetta-personalizzata-sposi-cartoon-millefiori-135-g\/\">48 Bomboniere miele matrimonio &#8211; vasetto miele millefiori 135g.<\/a><\/h3>            \n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>381,12<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Il prezzo originale era: 381,12&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>343,20<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Il prezzo attuale \u00e8: 343,20&euro;.<\/span><\/span>\n            <div class=\"product-caption-bottom\">\n                <a class=\"button product_type_simple add_to_cart_button button-reverse reverse\" href=\"https:\/\/bo2.x-brain.it\/en\/configurator\/#\/?id_store_products=754&id_woocommerce=29239\">Personalizza<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29239\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li>\n<li class=\"product-style-default product type-product post-29238 status-publish first instock product_cat-matrimoni product_tag-liquore product_tag-small-format has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n    <div class=\"product-block\">\n        <div class=\"content-product-imagin\"><\/div>\n        <div class=\"product-transition\">\n            <div class=\"product-image image-main\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c270c75bca7.54757736.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"N\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c270c75bca7.54757736.jpeg 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c270c75bca7.54757736-300x300.jpeg 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c270c75bca7.54757736-768x768.jpeg 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c270c75bca7.54757736-450x450.jpeg 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c270c75bca7.54757736-100x100.jpeg 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c270c75bca7.54757736-50x50.jpeg 50w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c270c75bca7.54757736-460x460.jpeg 460w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/div>                                                <div class=\"group-action\">\n                <div class=\"shop-action vertical\">\n                                    <\/div>\n            <\/div>\n            <a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/bomboniere-liquore-limone-bottiglie-mignon-personalizzate-matrimonio-limoncello-anelli-nomi\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            <\/a>        <\/div>\n        <div class=\"product-caption\">\n            <h3 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/bomboniere-liquore-limone-bottiglie-mignon-personalizzate-matrimonio-limoncello-anelli-nomi\/\">24 bottiglie mignon 0.10 lt. &#8211; Limoncello per bomboniere matrimonio<\/a><\/h3>            \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>222,96<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n            <div class=\"product-caption-bottom\">\n                <a class=\"button product_type_simple add_to_cart_button button-reverse reverse\" href=\"https:\/\/bo2.x-brain.it\/en\/configurator\/#\/?id_store_products=753&id_woocommerce=29238\">Personalizza<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29238\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li>\n<li class=\"product-style-default product type-product post-29237 status-publish instock product_cat-matrimoni product_tag-sweet has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n    <div class=\"product-block\">\n        <div class=\"content-product-imagin\"><\/div>\n        <div class=\"product-transition\">\n            <div class=\"product-image image-main\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c24b93927c9.23428476.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"N\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c24b93927c9.23428476.jpeg 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c24b93927c9.23428476-300x300.jpeg 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c24b93927c9.23428476-768x768.jpeg 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c24b93927c9.23428476-450x450.jpeg 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c24b93927c9.23428476-100x100.jpeg 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c24b93927c9.23428476-50x50.jpeg 50w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c24b93927c9.23428476-460x460.jpeg 460w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/div>            \n\t<span class=\"onsale\">15% DI SCONTO<\/span>\n\t                                    <div class=\"group-action\">\n                <div class=\"shop-action vertical\">\n                                    <\/div>\n            <\/div>\n            <a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/vasetto-cioccolata-personalizzata-idea-bomboniere-personalizzate-matrimonio-sposi-cuore-rosso\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            <\/a>        <\/div>\n        <div class=\"product-caption\">\n            <h3 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/vasetto-cioccolata-personalizzata-idea-bomboniere-personalizzate-matrimonio-sposi-cuore-rosso\/\">24 vasetti &#8211; Cioccolata personalizzata bomboniere matrimonio<\/a><\/h3>            \n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>390,24<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Il prezzo originale era: 390,24&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>331,68<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Il prezzo attuale \u00e8: 331,68&euro;.<\/span><\/span>\n            <div class=\"product-caption-bottom\">\n                <a class=\"button product_type_simple add_to_cart_button button-reverse reverse\" href=\"https:\/\/bo2.x-brain.it\/en\/configurator\/#\/?id_store_products=752&id_woocommerce=29237\">Personalizza<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29237\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li>\n<li class=\"product-style-default product type-product post-29236 status-publish instock product_cat-matrimoni product_tag-distillati product_tag-small-format has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n    <div class=\"product-block\">\n        <div class=\"content-product-imagin\"><\/div>\n        <div class=\"product-transition\">\n            <div class=\"product-image image-main\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c2007886f33.75337898.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"N\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c2007886f33.75337898.jpeg 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c2007886f33.75337898-300x300.jpeg 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c2007886f33.75337898-768x768.jpeg 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c2007886f33.75337898-450x450.jpeg 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c2007886f33.75337898-100x100.jpeg 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c2007886f33.75337898-50x50.jpeg 50w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-642c2007886f33.75337898-460x460.jpeg 460w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/div>                                                <div class=\"group-action\">\n                <div class=\"shop-action vertical\">\n                                    <\/div>\n            <\/div>\n            <a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/bomboniere-matrimonio-gin-bottiglie-mignon-personalizzate-idea-originale-grey-flower\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            <\/a>        <\/div>\n        <div class=\"product-caption\">\n            <h3 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/bomboniere-matrimonio-gin-bottiglie-mignon-personalizzate-idea-originale-grey-flower\/\">48 Bomboniere Gin &#8211; bottiglie mignon 0.10 lt. &#8211; Mini bottiglie idea per bomboniere matrimonio<\/a><\/h3>            \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>441,12<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n            <div class=\"product-caption-bottom\">\n                <a class=\"button product_type_simple add_to_cart_button button-reverse reverse\" href=\"https:\/\/bo2.x-brain.it\/en\/configurator\/#\/?id_store_products=751&id_woocommerce=29236\">Personalizza<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29236\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li>\n<li class=\"product-style-default product type-product post-29235 status-publish last instock product_cat-matrimoni product_tag-liquore product_tag-small-format has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n    <div class=\"product-block\">\n        <div class=\"content-product-imagin\"><\/div>\n        <div class=\"product-transition\">\n            <div class=\"product-image image-main\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6421bd024fa8f0.04868141.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"N\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6421bd024fa8f0.04868141.jpeg 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6421bd024fa8f0.04868141-300x300.jpeg 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6421bd024fa8f0.04868141-768x768.jpeg 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6421bd024fa8f0.04868141-450x450.jpeg 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6421bd024fa8f0.04868141-100x100.jpeg 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6421bd024fa8f0.04868141-50x50.jpeg 50w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2025\/10\/img-6421bd024fa8f0.04868141-460x460.jpeg 460w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/div>                                                <div class=\"group-action\">\n                <div class=\"shop-action vertical\">\n                                    <\/div>\n            <\/div>\n            <a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/bomboniere-liquore-limone-bottiglie-mignon-personalizzate-matrimonio-limoncello-cornice-gold-nomi\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">            <\/a>        <\/div>\n        <div class=\"product-caption\">\n            <h3 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/bo2.x-brain.it\/it\/vetrina\/bomboniere-liquore-limone-bottiglie-mignon-personalizzate-matrimonio-limoncello-cornice-gold-nomi\/\">36 Bomboniere matrimonio &#8211; bottiglie mignon 0.10 lt. &#8211; Limoncello personalizzato idea per bomboniere matrimonio<\/a><\/h3>            \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>334,44<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\n            <div class=\"product-caption-bottom\">\n                <a class=\"button product_type_simple add_to_cart_button button-reverse reverse\" href=\"https:\/\/bo2.x-brain.it\/en\/configurator\/#\/?id_store_products=748&id_woocommerce=29235\">Personalizza<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29235\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/li>\n<\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-2d7c015 h-r4 mb-xl e-flex e-con-boxed e-con e-parent\" data-id=\"2d7c015\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-27450aa e-con-full title-c e-flex e-con e-child\" data-id=\"27450aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-151b76b h2-bic-cat-wt elementor-widget elementor-widget-xbtitle\" data-id=\"151b76b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"xbtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t    <div class=\"xb-title-widget\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"xb-title\">Personalizza ogni evento: scegli i vini e le bomboniere gastronomiche Bottle-Up!<\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"xb-description\"><p>Diventa nostro partner e offri ai tuoi clienti un servizio unico<\/p><\/div>\r\n\t\t\t\t    <\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e9196b e-con-full 4-block e-flex e-con e-child\" data-id=\"2e9196b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b68e4f1 e-con-full e-flex e-con e-child\" data-id=\"b68e4f1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be172a4 elementor-view-stacked ht-icon h4-vant-cat elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"be172a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1_serietv\" data-name=\"Livello_1_serietv\" viewBox=\"0 0 141.73 141.73\" fill=\"#7000FE\"><path d=\"M7.63,98.42V22.34c1-2.64,2.77-4.16,5.73-4.16,38.33,.01,76.65,0,114.98,.01,3.59,0,5.76,2.19,5.76,5.78,0,24.25,0,48.5,0,72.74,0,.53,0,1.08-.12,1.59-.59,2.73-2.71,4.23-5.97,4.23-16.76,0-33.51,0-50.27,0-.51,0-1.03,.05-1.54,.08v10.42c.54,0,.98,0,1.43,0,4.69,0,9.39-.03,14.08,0,5.07,.04,9.17,3.15,10.4,7.87,.22,.84,.27,1.72,.41,2.63H39.26c.03-.5,.03-.95,.09-1.38,.87-5.42,5.09-9.07,10.62-9.12,4.73-.04,9.47,0,14.2,0,.44,0,.88,0,1.37,0v-10.5h-1.64c-16.51,0-33.02-.04-49.52,.04-3.26,.02-5.58-1.01-6.75-4.15ZM60.4,47.24v26.26c7.05-4.41,13.96-8.73,21.01-13.13-7.1-4.44-13.99-8.74-21.01-13.12Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGestionale riservato\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAccesso al gestionale Bottle-Up riservato a Wedding Planner per richiesta di preventivi online\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1874c42 e-con-full e-flex e-con e-child\" data-id=\"1874c42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60f5a98 elementor-view-stacked ht-icon h4-vant-cat elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"60f5a98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1_partners\" data-name=\"Livello_1_partners\" viewBox=\"0 0 141.73 141.73\" fill=\"#7000FE\"><path d=\"M76.84,114.51c2.38-1.26,3.34-4.17,2.07-6.56,0,0-2.37-4.45-3.67-6.87-.66,3.13-2.49,4.18-6.81,7.92l1.87,3.51c.85,1.58,4.12,3.29,6.54,2Zm-12.53-5.65l6.64-5.75c2.23-1.95,2.12-5.28,.21-7.12-1.84-1.87-4.77-1.85-6.59-.26l-6.64,5.77c-2.05,1.77-2.21,4.84-.45,6.87,1.53,1.74,4.59,2.41,6.84,.49Zm23.31-.06c2.53-1.36,3.26-4.29,2.07-6.58l-7.51-14.02,2.13-1.34,8.35,15.77c1.25,2.35,4.14,3.24,6.54,2.01,2.5-1.35,3.3-4.26,2.07-6.58l-8.68-16.36,2.21-1.33s5.74,11.06,7.81,14.99c1.28,2.38,4.24,3.24,6.55,2,2.43-1.28,3.33-4.17,2.07-6.58-6.5-12.32-5.09-9.73-7.74-14.07-7.83-10.87-19.24-18.33-30.48-27.64l-19.97,9.38c-4.13,1.9-8.47-.08-10.18-3.61-1.87-3.89-.22-8.42,3.56-10.26l4.78-2.24-15.35-.04-16.26,22.25,10.6,9.75c.45-.98,1.11-1.86,1.93-2.58l11.9-10.33c3.17-2.71,7.98-2.43,10.78,.76,1.39,1.61,2.05,3.6,1.89,5.64,2.78-.63,5.6,.37,7.42,2.44,2.23,2.57,2.52,6.19,.81,8.98,1.78,.29,3.38,1.17,4.55,2.53,2.62,3.03,2.48,7.41-.08,10.2,1.75-.26,3.82,.67,4.79,2.17,0,0,5.07,9.2,6.91,12.69,.83,1.58,4.13,3.29,6.54,2Zm-31.31-9.16l10.6-9.19c1.99-1.71,2.24-4.78,.43-6.87-1.72-2-4.79-2.26-6.82-.48-.25,.22-10.74,9.3-10.97,9.54-1.69,1.81-1.71,4.61-.06,6.52,1.57,1.82,4.66,2.35,6.82,.48Zm-9.31-8.09l14.54-12.6c2.02-1.73,2.25-4.8,.45-6.87-1.79-2.04-4.82-2.23-6.82-.49l-13.27,11.48c-3.08,1.94-3.5,5.94-1.71,7.99,1.48,1.74,4.61,2.41,6.82,.48Zm-13.5-10.84c-1.8-2.09-1.54-5.16,.44-6.87l11.9-10.34c1.99-1.7,5.06-1.55,6.84,.49,1.79,2.08,1.6,5.1-.44,6.87l-11.92,10.34c-1.86,1.63-4.92,1.68-6.82-.49Zm39.93-34.94l-21.59,10.13c-2.54,1.19-5.34,.02-6.46-2.29-1.21-2.53-.11-5.36,2.26-6.52l21.73-10.19c3.02-1.1,6.04-1.6,9.74-1.6,7.47,0,22.81,4.02,29.87,6.03l12.69,21.64-7.28,4.59c-1.74,1.67-3.17,6.38-6.99,8.89-7.81-10.59-21.47-21.63-33.98-30.69Zm37.51-8.86l13.34-8.15,16.05,26.85-13.87,7.78-15.53-26.47ZM1.39,54.03L20.14,26.76l13.79,11.06L15.62,63.24,1.39,54.03Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCondizioni dedicate\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAccordi con commissioni percentuali sulle vendite o accordi di distribuzione diretta\n\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77d5681 e-con-full e-flex e-con e-child\" data-id=\"77d5681\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b60da elementor-view-stacked ht-icon h4-vant-cat elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c5b60da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1_termini_condizioni\" data-name=\"Livello_1_termini_condizioni\" viewBox=\"0 0 141.73 141.73\" fill=\"#7000FE\"><path d=\"M126.14,15h-21.04v-5.78H36.72L8.73,37.22v95.36H105.1v-5.78h21.04V15h0Zm-39.65,104.56H27.34v-7.71h59.14v7.71Zm0-14.7H27.34v-7.71h59.14v7.71Zm-4.8-43.36v7.71H32.14v-7.71h49.55Zm-49.55-7.95v-7.71h49.55v7.71H32.14Zm59.14-15.74H22.54v-7.71H91.28v7.71Zm27.46,81.59h-13.64V22.4h13.65V119.4h0Z\"><\/path><polygon points=\"8.73 9.23 8.73 26.32 25.82 9.23 8.73 9.23\"><\/polygon><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tBooklet e sample\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFornitura booklet cartaceo con sample etichette e listino prodotti completo\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73b72d8 e-con-full e-flex e-con e-child\" data-id=\"73b72d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e81d86b elementor-view-stacked ht-icon h4-vant-cat elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"e81d86b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1_supporto_grafico\" data-name=\"Livello_1_supporto_grafico\" viewBox=\"0 0 141.73 141.73\" fill=\"#7000FE\"><polygon points=\"67.09 74.48 80.45 47.01 97.95 29.09 6.39 29.09 6.39 106.06 55.43 106.06 55.43 130.32 27.37 130.32 27.37 135.66 103.27 135.66 103.27 130.32 75.21 130.32 75.21 106.06 124.25 106.06 124.25 32.05 95.18 61.13 67.09 74.48\"><\/polygon><path d=\"M94.24,55.59c8.76-8.81,17.55-17.65,26.35-26.5,4.92-4.95,9.84-9.89,14.75-14.84-2.71-2.7-5.53-5.51-8.22-8.19-7.71,7.67-15.43,15.35-23.15,23.02-6.07,6.03-12.13,12.07-18.19,18.09,2.9,2.88,5.7,5.66,8.46,8.41Z\"><\/path><path d=\"M81.74,50.11c-2.97,6.06-5.92,12.13-8.87,18.2-.07,.15-.13,.32-.28,.68,6.83-3.42,13.47-6.75,20.06-10.05-3.39-3.37-6.68-6.65-10.04-9.98-.22,.29-.64,.67-.87,1.15Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSupporto grafico \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tper la realizzazione di etichette per bomboniere gastronomiche e bottiglie personalizzate\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-2b6feef elementor-section-stretched elementor-section-content-middle h-r3 h-r3-reverse mb-xl elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b6feef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c0ee8df\" data-id=\"c0ee8df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6aa25c4 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6aa25c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1446\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/1-scaled.webp\" class=\"attachment-full size-full wp-image-64031\" alt=\"1\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Etichette personalizzate in stampa digitale sempre incluse nel prezzo<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-af61f6e\" data-id=\"af61f6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7efa2c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f7efa2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1446\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/2-1-scaled.webp\" class=\"attachment-full size-full wp-image-64036\" alt=\"2\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Etichette sagomate a partire da 36 bottiglie personalizzate<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-8d33dd9 elementor-section-stretched elementor-section-content-middle h-r3 h-r3-reverse mb-xl elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d33dd9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65901ef\" data-id=\"65901ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12ee762 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"12ee762\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1446\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/3-1-scaled.webp\" class=\"attachment-full size-full wp-image-64053\" alt=\"3\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Etichette personalizzate luxury in stampa UV con oro, argento e rilievi<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30faa1a\" data-id=\"30faa1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d71385 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0d71385\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1446\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/4-1-scaled.webp\" class=\"attachment-full size-full wp-image-64051\" alt=\"4\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Esclusiva etichetta a fascia che avvolge a 360\u00b0 la bottiglia<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-3c94e33 elementor-section-stretched elementor-section-content-middle h-r3 h-r3-reverse mb-xl elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c94e33\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3768296\" data-id=\"3768296\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ed7100 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5ed7100\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1446\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/5-scaled.webp\" class=\"attachment-full size-full wp-image-64049\" alt=\"5\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Incisione su vetro e pittura a mano in oro e argento senza minimo d'ordine<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7066b93\" data-id=\"7066b93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d26c88 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0d26c88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1446\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/6-scaled.webp\" class=\"attachment-full size-full wp-image-64047\" alt=\"6\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Spumanti con etichetta sleeve a 360\u00b0 a partire da 300 pezzi<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61e5573 pt-xl title-c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61e5573\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d46d12\" data-id=\"1d46d12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f1b758 h2-bic-cat elementor-widget elementor-widget-xbtitle\" data-id=\"5f1b758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"xbtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t    <div class=\"xb-title-widget\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"xb-title\">Proponi agli sposi un\u2019idea <span>unica e originale<\/span>!<\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"xb-description\"><p>Bottiglie personalizzate a tema, con vini, spumanti e birre in abbinamento al menu del matrimonio. Bottiglie personalizzate in piccolo formato per bomboniere gastronomiche: 0.10L, 0.20L, 0.25L, 0.50L<\/p><\/div>\r\n\t\t\t\t    <\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5698f6 product-2-rows elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5698f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-687c9d4\" data-id=\"687c9d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04d1911 e-grid e-con-boxed e-con e-parent\" data-id=\"04d1911\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-081926d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"081926d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/7-1.webp\" class=\"attachment-full size-full wp-image-64062\" alt=\"7\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/7-1.webp 1080w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/7-1-300x300.webp 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/7-1-1024x1024.webp 1024w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/7-1-768x768.webp 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/7-1-450x450.webp 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/7-1-800x800.webp 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/7-1-100x100.webp 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/7-1-50x50.webp 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Ampia gamma di prodotti selezionati da tutta Italia: vini, spumanti, birre artigianali e liquori, olio da Toscana, Puglia e Sicilia<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46a7e0f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"46a7e0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/8.webp\" class=\"attachment-full size-full wp-image-64060\" alt=\"8\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/8.webp 1080w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/8-300x300.webp 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/8-1024x1024.webp 1024w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/8-768x768.webp 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/8-450x450.webp 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/8-800x800.webp 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/8-100x100.webp 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/8-50x50.webp 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Bottiglie personalizzate per bomboniere gastronomiche disponibili in piccolo formato: 0.10L, 0.20L, 0.25L, 0.33L, 0.375L<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c7572 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"34c7572\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/9.webp\" class=\"attachment-full size-full wp-image-64058\" alt=\"9\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/9.webp 1080w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/9-300x300.webp 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/9-1024x1024.webp 1024w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/9-768x768.webp 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/9-450x450.webp 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/9-800x800.webp 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/9-100x100.webp 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/9-50x50.webp 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Prosecco, Franciacorta e Metodo Classico, in formato mignon per bomboniere gastronomiche e magnum per il brindisi finale<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adac670 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"adac670\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/10-1.webp\" class=\"attachment-full size-full wp-image-64056\" alt=\"10\" srcset=\"https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/10-1.webp 1080w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/10-1-300x300.webp 300w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/10-1-1024x1024.webp 1024w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/10-1-768x768.webp 768w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/10-1-450x450.webp 450w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/10-1-800x800.webp 800w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/10-1-100x100.webp 100w, https:\/\/bo2.x-brain.it\/wp-content\/uploads\/2026\/01\/10-1-50x50.webp 50w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Brunello di Montalcino, Chianti, Barolo e Amarone, come regalo ai testimoni del matrimonio o in abbinamento al menu<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-5e90fa9 elementor-section-stretched pb-xl pt-xl banner-servizi-aziende elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e90fa9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67156c7\" data-id=\"67156c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77c35d2 h2-bic-cat-wt title-c  elementor-widget elementor-widget-xbtitle\" data-id=\"77c35d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"xbtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t    <div class=\"xb-title-widget\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"xb-title\">I nostri servizi<\/h3>\r\n\t\t\t\r\n\t\t\t\t    <\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-4444a21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4444a21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c237d54\" data-id=\"c237d54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef7c5e0 elementor-view-stacked elementor-position-inline-start elementor-tablet-position-block-start elementor-mobile_extra-position-block-start elementor-widget-mobile_extra__width-initial elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ef7c5e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1_fc_assistenza_clienti\" data-name=\"Livello_1_fc_assistenza_clienti\" viewBox=\"0 0 141.73 141.73\" fill=\"#7000FE\"><path d=\"M70.87,76.63c-23.86,0-43.21,19.34-43.21,43.21,0,6.36,5.16,11.52,11.52,11.52h63.37c6.36,0,11.52-5.16,11.52-11.52,0-23.86-19.34-43.21-43.21-43.21Z\"><\/path><path d=\"M110.13,37.91c-5.83-16.04-21.23-27.53-39.27-27.53s-33.43,11.49-39.27,27.53c-4.69,.86-8.26,4.98-8.26,9.91,0,5.56,4.52,10.08,10.08,10.08h4.32v-5.76c0-18.27,14.86-33.13,33.13-33.13s33.13,14.86,33.13,33.13v5.76h4.32c5.56,0,10.08-4.52,10.08-10.08,0-4.94-3.57-9.05-8.26-9.91Z\"><\/path><path d=\"M70.87,27.66c-13.52,0-24.48,10.96-24.48,24.48,0,.98,.06,1.94,.17,2.88h15.62c1.02-.89,2.34-1.44,3.8-1.44,3.18,0,5.76,2.58,5.76,5.76,0,1.54-.6,2.99-1.69,4.07-1.09,1.09-2.53,1.69-4.07,1.69h0c-1.45,0-2.78-.55-3.8-1.44h-12.91c4.12,7.71,12.25,12.96,21.61,12.96,13.52,0,24.48-10.96,24.48-24.48s-10.96-24.48-24.48-24.48Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGestione a 360\u00b0\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGestione dell\u2019intero processo produttivo: consulenza selezione prodotto, supporto grafico, logistica e spedizioni \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cd9fdd1\" data-id=\"cd9fdd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddb80d4 elementor-view-stacked elementor-position-inline-start elementor-tablet-position-block-start elementor-mobile_extra-position-block-start elementor-widget-mobile_extra__width-initial elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ddb80d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1_sconti\" data-name=\"Livello_1_sconti\" viewBox=\"0 0 141.73 141.73\" fill=\"#7000FE\"><path d=\"M119.15,66.11c-.03-13.74-.01-27.49-.04-41.23,0-.76,.3-1.48,.84-2.01,3.21-3.15,6.38-6.34,9.57-9.53,1.54-1.54,1.52-2.45-.08-3.84-.55,.02-.94,.03-1.49,.05-.64,.61-1.35,1.16-1.92,1.83-2.86,3.4-5.3,5.44-8.52,8.58-.68,.67-1.6,1.04-2.55,1.04h-4.01c-.57,0-.91,0-1.25,0-11.95,0-23.91,0-35.86-.02-.98,0-1.92,.39-2.61,1.08C50.49,42.84,29.73,63.59,8.98,84.35c-.37,.37-.7,.76-1.05,1.14,0,.54,0,.88,.02,1.42,.66,.69,1.3,1.38,1.97,2.06,14,14.01,28.01,28.01,42.02,42.02,1.66,1.66,2.4,1.66,4.08-.02,20.64-20.64,41.28-41.29,61.94-61.91,.78-.78,1.22-1.84,1.22-2.94Zm-64.27,8.05c-3.05,2.06-7.17,1.31-9.33-1.7-.05-.07-.12-.13-.18-.19-.22-.43-.44-.85-.66-1.28-.01-.07-.01-.15-.03-.22-.8-2.48-.36-4.73,1.32-6.71,.4-.47,.92-.84,1.39-1.26,.38-.2,.76-.39,1.14-.59,.75-.15,1.49-.39,2.24-.44,3.06-.18,5.78,1.75,6.77,4.72,.92,2.77-.19,5.99-2.66,7.66Zm2.45,20.69s.12-.17,.17-.31c4.63-14.63,9.26-29.26,13.88-43.89,.03-.08,.04-.17,.06-.25l.07-.03c.13,.05,.25,.11,.38,.16,2.17,.69,4.35,1.38,6.52,2.07,.13,.04,.26,.09,.43,.15-4.7,14.86-9.39,29.7-14.07,44.52-2.46-.79-4.89-1.58-7.43-2.4Zm30.78-9.41c-3.32,1.71-7.4,.4-9.12-2.93-1.72-3.33-.42-7.41,2.91-9.12,3.33-1.71,7.41-.41,9.13,2.92,1.71,3.32,.4,7.42-2.92,9.13Z\"><\/path><path d=\"M133.72,34.19c-.4-.59-.9-1.5-1.42-1.54-2.04-.18-4.1-.07-6.2-.07v1.56c0,10.62-.04,21.24,.03,31.86,.01,2.37-.77,4.18-2.44,5.85-17.14,17.08-34.23,34.2-51.35,51.3-.33,.33-.8,.53-1.39,.91,1.49,1.42,2.66,2.51,3.79,3.62,1.62,1.6,2.38,1.61,4-.01,17.95-17.96,35.9-35.92,53.87-53.86,.82-.82,1.18-1.69,1.18-2.86-.03-11.9-.02-23.8-.02-35.69,0-.36,.12-.81-.05-1.06Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSconti quantit\u00e0\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSconti in base al numero di bottiglie personalizzate acquistate \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-6041334 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6041334\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-60a991a\" data-id=\"60a991a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98d4f22 elementor-view-stacked elementor-position-inline-start elementor-tablet-position-block-start elementor-mobile_extra-position-block-start elementor-widget-mobile_extra__width-initial elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"98d4f22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1_Fc_prodotti\" data-name=\"Livello_1_Fc_prodotti\" viewBox=\"0 0 141.73 141.73\" fill=\"#7000FE\"><g><path d=\"M22.41,8.99c-1.65,0-3.3,.02-4.94,0-1.31-.02-2.05-.87-2.06-2.26-.02-1.4,.73-2.31,2.01-2.32,3.33-.03,6.67-.03,10,0,1.28,.01,2.02,.93,2.01,2.32-.02,1.39-.76,2.23-2.07,2.25-1.65,.03-3.3,0-4.94,0Z\"><\/path><path d=\"M41.29,130.08c0-24.37,.02-48.74,0-73.11,0-3.12-.84-5.98-2.38-8.58-.44-.74-.93-1.47-1.48-2.17-2.22-2.82-5.11-4.7-8.55-6.05V9.12H15.89c0,.7,0,1.24,0,1.78,0,9.34-.01,18.68,.02,28.02,0,.97-.27,1.41-1.19,1.83-7.01,3.21-11.1,8.62-11.13,16.43-.1,25.46-.04,50.93-.03,76.39,0,.59,.04,1.18,.16,1.75,.44,2.11,1.18,2.72,3.33,2.72,4.03,.01,8.06,0,12.09,0,6.24,0,12.48,0,18.73,0,2.08,0,2.8-.6,3.25-2.64,.12-.52,.18-1.07,.18-1.6,0-1.24,0-2.48,0-3.72Z\"><\/path><\/g><g><path d=\"M116.91,7.69c-.62-.06-1.04-.1-1.45-.14-.01-1.96,1.02-3.49,2.79-3.61,2.7-.18,5.41-.18,8.11,0,1.76,.11,2.73,1.41,3.1,3.53-.45,.08-.89,.16-1.52,.28,.11,1.57,.21,3.14,.35,4.71,1.02,11.57,2.01,23.14,3.11,34.7,.15,1.53,.67,3.16,1.41,4.45,3.21,5.62,4.8,11.87,5.18,18.49,.3,5.14,.2,10.32,.21,15.49,.02,15.05,.01,30.09,.01,45.14,0,4.62-2.06,7.15-5.98,7.17-6.66,.04-13.32,.04-19.97,0-3.89-.02-5.85-2.4-5.85-6.91,0-18.66,0-37.32,0-55.97,0-7.02,1.1-13.75,3.81-20.06,.4-.93,1.03-1.75,1.38-2.7,.63-1.72,1.45-3.47,1.64-5.28,1.19-11.65,2.23-23.31,3.32-34.97,.13-1.39,.24-2.78,.36-4.3Z\"><\/path><path d=\"M72.69,97.97c-.77-.8-1.52-1.62-2.23-2.47-.25-.3-.43-.69-.51-1.07-.11-.49-.34-.68-.83-.67-.85,.02-1.7,0-2.7,0h-16.88c-.16,0-.32,0-.48,0-.34,0-.49,.21-.61,.51-.19,.49-.36,1.01-.68,1.41-.65,.81-1.42,1.54-2.1,2.33-.19,.22-.37,.55-.38,.83-.02,11.32-.02,22.65,0,33.97,0,.28,.18,.61,.37,.83,.69,.8,1.45,1.55,2.14,2.36,.27,.32,.49,.73,.61,1.14,.22,.72,.23,.77,.98,.77,6.53,0,13.07,0,19.6,0,.1,0,.19,0,.29,0,.34,0,.51-.19,.63-.5,.16-.4,.31-.82,.57-1.15,.71-.89,1.5-1.73,2.23-2.61,.2-.24,.37-.59,.37-.89,.02-11.29,.01-22.58,.02-33.88,0-.39-.14-.65-.41-.93Z\"><\/path><\/g><path d=\"M67.23,81.21h36.4c-.24,.42-.44,.76-.64,1.1-5.34,9.04-10.69,18.07-16.01,27.12-.19,.33-.32,.8-.32,1.21-.02,5.32,0,10.65-.02,15.97,0,.47,.12,.77,.41,1.07,2.48,2.58,4.95,5.18,7.42,7.78,.61,.64,.79,1.25,.56,1.91-.27,.77-.79,.95-1.42,.95-5.46-.01-10.92-.01-16.38,0-.64,0-1.16-.19-1.42-.96-.23-.67-.05-1.25,.57-1.91,2.46-2.58,4.91-5.17,7.38-7.73,.32-.33,.45-.68,.45-1.19-.01-5.3,0-10.6-.02-15.9,0-.41-.13-.88-.33-1.21-5.42-9.21-10.86-18.41-16.3-27.61-.1-.17-.2-.36-.33-.6Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFlessibilit\u00e0 scelta prodotti\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPossibilit\u00e0 di selezionare pi\u00f9 referenze nello stesso ordine \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7487e5e\" data-id=\"7487e5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee1adc2 elementor-view-stacked elementor-position-inline-start elementor-tablet-position-block-start elementor-mobile_extra-position-block-start elementor-widget-mobile_extra__width-initial elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ee1adc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1_no_minimo_ordine\" data-name=\"Livello_1_no_minimo_ordine\" viewBox=\"0 0 141.73 141.73\" fill=\"#7000FE\"><path d=\"M56.7,8.64c-1.65,0-3.3,.02-4.94,0-1.31-.02-2.05-.87-2.06-2.26-.02-1.4,.73-2.31,2.01-2.32,3.33-.03,6.67-.03,10,0,1.28,.01,2.02,.93,2.01,2.32-.02,1.39-.76,2.23-2.07,2.25-1.65,.03-3.3,0-4.94,0Z\"><\/path><path d=\"M75.58,129.73c0-24.37,.02-48.74,0-73.11,0-3.12-.84-5.98-2.38-8.58-.44-.74-.93-1.47-1.48-2.17-2.22-2.82-5.11-4.7-8.55-6.05V8.76h-12.99c0,.7,0,1.24,0,1.78,0,9.34-.01,18.68,.02,28.02,0,.97-.27,1.41-1.19,1.83-7.01,3.21-11.1,8.62-11.13,16.43-.1,25.46-.04,50.93-.03,76.39,0,.59,.04,1.18,.16,1.75,.44,2.11,1.18,2.72,3.33,2.72,4.03,.01,8.06,0,12.09,0,6.24,0,12.48,0,18.73,0,2.08,0,2.8-.6,3.25-2.64,.12-.52,.18-1.07,.18-1.6,0-1.24,0-2.48,0-3.72Z\"><\/path><path d=\"M89.02,36.83c0-1.36,0-2.73,0-4.09,0-.84,.07-.91,.88-.91,1.07,0,2.14,.04,3.21,0,.67-.02,.87,.27,.86,.9-.02,2.68-.02,5.37-.02,8.05,0,1,.03,1.02,1.05,1.03,2.66,0,5.32,0,7.98,.01,.84,0,.93,.1,.93,.95,0,1.02,0,2.05,0,3.07,0,.78-.12,.9-.91,.91-2.71,0-5.41,0-8.12,0-.88,0-.93,.06-.93,.93,0,2.71,0,5.41-.01,8.12,0,.79-.13,.92-.9,.92-1.07,0-2.14-.02-3.21,.02-.62,.02-.85-.23-.84-.84,.02-2.73,.02-5.46,.02-8.19,0-.91-.05-.96-.97-.96-2.68,0-5.37,0-8.05,0-.86,0-.94-.09-.94-.93,0-1.05,0-2.09,0-3.14,0-.81,.08-.88,.92-.88,2.71,0,5.41,.02,8.12,.02,.86,0,.93-.07,.93-.94,0-1.34,0-2.68,0-4.03Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOrdine minimo\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMinimo d\u2019ordine a partire da 36 bottiglie\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3da1099 title-c  elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3da1099\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81f234f\" data-id=\"81f234f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e25218b title-c pt-xl elementor-widget elementor-widget-xbtitle\" data-id=\"e25218b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"xbtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t    <div class=\"xb-title-widget\">\r\n\t\t\t\t\t\t\t<h3 class=\"xb-subtitle\">I nostri clienti<\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"xb-title\">Cosa dicono <span>di noi<\/span><\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"xb-description\"><p>Scopri cosa pensano i nostri clienti della loro esperienza con noi.<\/p><\/div>\r\n\t\t\t\t    <\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ea972f pb-xl title-section block-title elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ea972f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af84d8d\" data-id=\"af84d8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6dbaa2 testimonial-column-3 testimonial-column-3 testimonial-column-3 testimonial-column-2 testimonial-column-2 testimonial-column-1 carousel-visible-left dot-style-2 block-review arrow-style-1 elementor-widget elementor-widget-xbtestimonials\" data-id=\"a6dbaa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:5000}\" data-widget_type=\"xbtestimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"elementor-testimonial-item-wrapper\">\n                <div class=\"row layout-2 alignment-left row printec-carousel\" data-settings=\"{&quot;centerMode&quot;:false,&quot;variableWidth&quot;:true,&quot;speed&quot;:300,&quot;centerPadding&quot;:&quot;50px&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;pauseOnHover&quot;:true,&quot;autoplay&quot;:true,&quot;autoplaySpeed&quot;:5000,&quot;items&quot;:&quot;3&quot;,&quot;items_laptop&quot;:&quot;3&quot;,&quot;items_tablet_extra&quot;:&quot;3&quot;,&quot;items_tablet&quot;:&quot;2&quot;,&quot;items_mobile_extra&quot;:&quot;2&quot;,&quot;items_mobile&quot;:&quot;1&quot;,&quot;loop&quot;:true,&quot;breakpoint_laptop&quot;:1440,&quot;breakpoint_tablet_extra&quot;:1200,&quot;breakpoint_tablet&quot;:1024,&quot;breakpoint_mobile_extra&quot;:880,&quot;breakpoint_mobile&quot;:767,&quot;centerPadding_laptop&quot;:&quot;50px&quot;,&quot;centerPadding_tablet_extra&quot;:&quot;50px&quot;,&quot;centerPadding_tablet&quot;:&quot;50px&quot;,&quot;centerPadding_mobile_extra&quot;:&quot;50px&quot;,&quot;centerPadding_mobile&quot;:&quot;50px&quot;}\">\n                    \n                        <div class=\"column-item elementor-testimonial-item\">\n                            <div class=\"inner\">\n                                <div class=\"elementor-testimonial-rating\"><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><\/div>                                <div class=\"testimonial-content\">\n                                                                            <div class=\"content\">\n<p>Bellissima idea di personalizzare le bottiglie a tema Festa della Mamma! Stampe perfette, ottimo rapporto qualit\u00e0 prezzo! Acquister\u00f2 sicuramente di nuovo i loro prodotti. Consigliatissimi!<\/p>\n\n\n\n<p><\/p>\n<\/div>\n                                                                        <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Sonia Csucsak<\/span>                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    \n                        <div class=\"column-item elementor-testimonial-item\">\n                            <div class=\"inner\">\n                                <div class=\"elementor-testimonial-rating\"><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><\/div>                                <div class=\"testimonial-content\">\n                                                                            <div class=\"content\">\n<p>Bottle-Up \u00e8 una garanzia e puoi scegliere tra svariati prodotti e tutti di qualit\u00e0. Io ho scelto una bottiglia di vino rosso personalizzata per la Festa della Mamma, \u00e8 stata un successo!<\/p>\n<\/div>\n                                                                        <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Marco<\/span>                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    \n                        <div class=\"column-item elementor-testimonial-item\">\n                            <div class=\"inner\">\n                                <div class=\"elementor-testimonial-rating\"><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><\/div>                                <div class=\"testimonial-content\">\n                                                                            <div class=\"content\">\n<p>Ho acquistato una bottiglia di vino con etichetta personalizzata per la festa della mamma, per fare degli auguri speciali. Esperienza molto positiva, azienda seria, disponibile al dialogo con il cliente. Velocit\u00e0 nella consegna, assolutamente da consigliare. Splendide idee regalo. Grazie<\/p>\n<\/div>\n                                                                        <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Antonella Campa<\/span>                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    \n                        <div class=\"column-item elementor-testimonial-item\">\n                            <div class=\"inner\">\n                                <div class=\"elementor-testimonial-rating\"><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><\/div>                                <div class=\"testimonial-content\">\n                                                                            <div class=\"content\">\n<p>Queste bottiglie sono davvero molto belle a vedersi, ho acquistato per la Festa della Mamma, i vini sono molto buoni, spedizione veloce, l'imballo era perfetto, e la consegna puntuale.<\/p>\n<\/div>\n                                                                        <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Alessandro<\/span>                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    \n                        <div class=\"column-item elementor-testimonial-item\">\n                            <div class=\"inner\">\n                                <div class=\"elementor-testimonial-rating\"><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><\/div>                                <div class=\"testimonial-content\">\n                                                                            <div class=\"content\">\n<p>Complimenti per il servizio impeccabile: spedito il giorno dopo aver fatto l'ordine e arrivato in neanche 24 h. L'etichetta \u00e8 molto bella e stampata bene, fa figura. Acquistato per la Festa della Mamma. Consiglio a tutti l'acquisto.<\/p>\n<\/div>\n                                                                        <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Elisabetta<\/span>                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    \n                        <div class=\"column-item elementor-testimonial-item\">\n                            <div class=\"inner\">\n                                <div class=\"elementor-testimonial-rating\"><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><i class=\"fas fa-star active\" aria-hidden=\"true\"><\/i><\/div>                                <div class=\"testimonial-content\">\n                                                                            <div class=\"content\">\n<p>\u00c8 la seconda volta che ordino e mi trovo benissimo. Le bottiglie per la Festa della Mamma sono perfette. Spedizione veloce! Se ci sono problemi, riesci a contattare l\u2019assistenza velocemente. Consiglio a tutti per idee regalo speciali e divertimento! Sono stati degli auguri speciali e apprezzatissimi!<\/p>\n<\/div>\n                                                                        <div class=\"details\">\n                                                                                <div class=\"details-info\">\n                                            <span class=\"name\">Svetlana Kiseleva<\/span>                                                                                    <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-8516307 elementor-section-full_width elementor-section-stretched help-block elementor-section-height-default elementor-section-height-default\" data-id=\"8516307\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-900da6e\" data-id=\"900da6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ef81ac elementor-widget elementor-widget-shortcode\" data-id=\"8ef81ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"33256\" class=\"elementor elementor-33256\" data-elementor-post-type=\"elementor-hf\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-56f037a elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"56f037a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b1bf08d\" data-id=\"b1bf08d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-215e180 e-con-full title-c n-h e-flex e-con e-child\" data-id=\"215e180\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf4328 h2-bic-cat-wt elementor-widget elementor-widget-xbtitle\" data-id=\"7bf4328\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"xbtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t    <div class=\"xb-title-widget\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t<h3 class=\"xb-title\">Hai bisogno di supporto?<\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t<div class=\"xb-description\"><p>Il nostro team \u00e8 qui per te: contattaci e ti assisteremo al pi\u00f9 presto.<\/p><p>\u00a0<\/p><\/div>\r\n\t\t\t\t    <\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fec9f7 elementor-align-center effect-icon-yes elementor-button-default elementor-widget elementor-widget-button\" data-id=\"1fec9f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/contatti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"printec-icon- printec-icon-right-arrow\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ho bisogno di aiuto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-985eb96 chiediciunpreventivo-container pb-xl e-flex e-con-boxed e-con e-parent\" data-id=\"985eb96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5363c2 elementor-widget elementor-widget-shortcode\" data-id=\"b5363c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"56244\" class=\"elementor elementor-56244\" data-elementor-post-type=\"elementor-hf\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9959d2 chiediciunpreventivo e-flex e-con-boxed e-con e-parent\" data-id=\"b9959d2\" data-element_type=\"container\" data-e-type=\"container\" id=\"chiediciunpreventivo\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3da4c46 block-title elementor-widget elementor-widget-heading\" data-id=\"3da4c46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Chiedici un <span style=\"color: var(--primary)\">preventivo<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae38dc5 elementor-widget elementor-widget-shortcode\" data-id=\"ae38dc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><style id=\"wpforms-css-vars-32979\">\n\t\t\t\t#wpforms-32979 {\n\t\t\t\t--wpforms-field-border-color: rgba(0, 0, 0, 0.25);\n--wpforms-field-border-color-spare: rgba(0, 0, 0, 0.25);\n--wpforms-field-text-color: rgba(0, 0, 0, 0.7);\n--wpforms-label-color: rgba(0, 0, 0, 0.85);\n--wpforms-label-sublabel-color: rgba(0, 0, 0, 0.55);\n--wpforms-background-color: rgba(0, 0, 0, 0);\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 20px;\n--wpforms-button-size-height: 48px;\n--wpforms-button-size-padding-h: 20px;\n--wpforms-button-size-margin-top: 15px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><style id=\"wpforms-css-vars-32979-custom-css\">\n\t\t\t\t#wpforms-32979 {\n\t\t\t\t\tli{display:block !important;}\r\nul{padding-top:10px;}\r\np{max-width:716px; margin:auto;}\r\nlabel,legend{font-weight:400;font-size:.85rem;line-height:.5rem;}\r\ninput{border-radius: 1.5rem;border:none;}\r\ntextarea{border-radius: 1.5rem;border:none;}\r\n.text-center{text-align:center;}\r\n.custom-submit{display:block;margin:0 auto;background-color:#7000fe;border-radius:1.5rem;padding-left:40px;padding-right:40px;padding-bottom:15px;padding-top:15px;height:auto;font-size:14px;font-weight:600;}\r\n.link-color{color:#7000fe}\r\n@media (max-width: 767px) {.two-col-mobile ul {display: flex;flex-wrap: wrap;gap: 8px 16px;margin: 0;padding: 0;padding-top:10px;list-style: none;}.two-col-mobile ul>li {width: calc(50% - 8px);}}\n\t\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full custom-form wpforms-render-modern\" id=\"wpforms-32979\"><form id=\"wpforms-form-32979\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"32979\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/it\/wp-json\/wp\/v2\/pages\/62405\" data-token=\"9d56937709fb37daf87e849a8564fa1d\" data-token-time=\"1784150212\"><noscript class=\"wpforms-error-noscript\">Abilita JavaScript nel browser per completare questo modulo.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Abilita JavaScript nel browser per completare questo modulo.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-32979-field_2-container\" class=\"wpforms-field wpforms-field-checkbox two-col-mobile wpforms-list-3-columns\" data-field-id=\"2\"><fieldset><legend class=\"wpforms-field-label\">A quale prodotto sei interessato? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-32979-field_2\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-32979-field_2_1\" name=\"wpforms[fields][2][]\" value=\"Vino\" aria-errormessage=\"wpforms-32979-field_2_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-32979-field_2_1\">Vino<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-32979-field_2_2\" name=\"wpforms[fields][2][]\" value=\"Birra\" aria-errormessage=\"wpforms-32979-field_2_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-32979-field_2_2\">Birra<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-32979-field_2_3\" name=\"wpforms[fields][2][]\" value=\"Olio\" aria-errormessage=\"wpforms-32979-field_2_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-32979-field_2_3\">Olio<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-32979-field_2_4\" name=\"wpforms[fields][2][]\" value=\"Superalcolici\" aria-errormessage=\"wpforms-32979-field_2_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-32979-field_2_4\">Superalcolici<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-32979-field_2_5\" name=\"wpforms[fields][2][]\" value=\"Acqua\" aria-errormessage=\"wpforms-32979-field_2_5-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-32979-field_2_5\">Acqua<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-32979-field_2_6\" name=\"wpforms[fields][2][]\" value=\"Vino Bianco\" aria-errormessage=\"wpforms-32979-field_2_6-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-32979-field_2_6\">Vino Bianco<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-32979-field_2_7\" name=\"wpforms[fields][2][]\" value=\"Vino Rosso\" aria-errormessage=\"wpforms-32979-field_2_7-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-32979-field_2_7\">Vino Rosso<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-32979-field_2_8\" name=\"wpforms[fields][2][]\" value=\"Spumante\" aria-errormessage=\"wpforms-32979-field_2_8-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-32979-field_2_8\">Spumante<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"checkbox\" id=\"wpforms-32979-field_2_9\" name=\"wpforms[fields][2][]\" value=\"Analcolici\" aria-errormessage=\"wpforms-32979-field_2_9-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-32979-field_2_9\">Analcolici<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-32979-field_3-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"3\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-32979-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-32979-field_4\">Ragione Sociale <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-32979-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"Ragione Sociale\" aria-errormessage=\"wpforms-32979-field_4-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-32979-field_14-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-32979-field_14\">Partita IVA <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-32979-field_14\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][14]\" placeholder=\"Partita IVA\" aria-errormessage=\"wpforms-32979-field_14-error\" required><\/div><\/div><\/div><\/div><\/div>\t\t<div id=\"wpforms-32979-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-32979-field_1\" >A Sociale Partita<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-32979-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-32979-field_6-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"6\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-32979-field_7-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-32979-field_7\">Quantit\u00e0 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-32979-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" placeholder=\"Quantit\u00e0\" step=\"any\" aria-errormessage=\"wpforms-32979-field_7-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-32979-field_8-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-32979-field_8\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-32979-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" placeholder=\"Email\" spellcheck=\"false\" aria-errormessage=\"wpforms-32979-field_8-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\"><div id=\"wpforms-32979-field_9-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-32979-field_9\">Telefono <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-32979-field_9\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][9]\" placeholder=\"Telefono\" aria-label=\"Telefono\" aria-errormessage=\"wpforms-32979-field_9-error\" required><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-32979-field_11-container\" class=\"wpforms-field wpforms-field-checkbox mx-auto\" data-field-id=\"11\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Caselle di Spunta <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-32979-field_11\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-32979-field_11_1\" name=\"wpforms[fields][11][]\" value=\"Ho letto e accettato l\u2019&lt;a href=&quot;\/privacy-policy&quot; class=&quot;link-color&quot;&gt;informativa sulla privacy&lt;\/a&gt; *\" aria-errormessage=\"wpforms-32979-field_11_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-32979-field_11_1\">Ho letto e accettato l\u2019<a href=\"\/privacy-policy\" class=\"link-color\">informativa sulla privacy<\/a> *<\/label><\/li><\/ul><\/fieldset><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-32979-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-32979-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-32979-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"32979\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/pages\/62405\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-32979\" class=\"wpforms-submit custom-submit\" data-alt-text=\"Invio in corso...\" data-submit-text=\"Richiedi il preventivo\" aria-live=\"assertive\" value=\"wpforms-submit\">Richiedi il preventivo<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/bo2.x-brain.it\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Caricamento\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wedding Planner Bottiglie personalizzate: servizio Wedding Planner Sei un Wedding Planner? Stupisci i tuoi sposi con le bottiglie personalizzate come bomboniere gastronomiche per il matrimonio o in abbinamento al menu Richiedi un preventivo Diventa un nostro partner Crea in pochi click la tua bottiglia personalizzata per il tuo regalo speciale Wooden box 1 bottle MAGNUM [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-62405","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/pages\/62405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/comments?post=62405"}],"version-history":[{"count":0,"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/pages\/62405\/revisions"}],"wp:attachment":[{"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/media?parent=62405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}