{"id":55899,"date":"2025-10-15T13:21:37","date_gmt":"2025-10-15T13:21:37","guid":{"rendered":"https:\/\/wordpress.bottle-up.com\/?page_id=55899"},"modified":"2026-01-15T16:29:55","modified_gmt":"2026-01-15T16:29:55","slug":"pagamenti","status":"publish","type":"page","link":"https:\/\/bo2.x-brain.it\/it\/pagamenti\/","title":{"rendered":"Pagamenti"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"55899\" class=\"elementor elementor-55899\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-613c0bd elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"613c0bd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea779b6 title title-c\" data-id=\"ea779b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-982f9b7 elementor-widget__width-initial paragraph paragraph-l elementor-widget elementor-widget-text-editor\" data-id=\"982f9b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Digita qui...\">La nostra politica sui pagamenti\u200b<\/h1>\n<\/br>\nAccettiamo pagamenti tramite PayPal (circuiti supportati: account Paypal, Visa, Visa Electron, Mastercard, Maestro, American Express, Discover e Carta Aura), carte di credito, Addebito SEPA, Apple Pay e Google Pay, tramite la piattaforma per pagamenti elettronici STRIPE. In caso di pagamento con Addebito SEPA potrebbero essere previsti di costi di gestione dal proprio istituto bancario.\n\nIn caso di pagamento non andato a buon fine per 3DS:AUTENTICATION ERROR, la invitiamo a ripetere il pagamento dell\u2019ordine avendo cura di inserire correttamente i dati della carta di credito e il codice monouso 3D Secure* richiesto per approvare la transazione.\n\nPer procedere con un nuovo tentativo di pagamento non \u00e8 necessario ripetere la personalizzazione delle bottiglie, poich\u00e9 pu\u00f2 recuperare l\u2019ordine nella sezione STORICO ORDINI della sua area utente. Una volta nella sezione le apparir\u00e0 una lista di tutti gli ordini da lei salvati, cliccando sul pulsante verde &#8216;Completa&#8217; a fianco dell\u2019ordine desiderato verr\u00e0 reindirizzato alla pagina di checkout dell\u2019ordine selezionato e potr\u00e0 procedere con un nuovo tentativo di pagamento.\n\nNel caso venisse restituito l\u2019errore 3DS:AUTENTICATION ERROR anche al successivo tentativo di pagamento, la invitiamo a controllare nell\u2019area clienti della carta utilizzata che il sistema di protezione anti frode 3D Secure, attivo sulla carta in oggetto, sia configurato correttamente per inviarle un codice monouso per approvare la transazione ogni volta che tenta di concludere un pagamento online. A seconda della societ\u00e0 che ha rilasciato la carta di credito e della modalit\u00e0 di invio indicate in fase di configurazione del servizio la password monouso pu\u00f2 essere inviata via sms, app per smartphone o dispositivo generatore di codici.\n\nIn alternativa pu\u00f2 utilizzare l\u2019opzione di pagamento, PayPal, e concludere l\u2019acquisto:\n<ul>\n \t<li>Utilizzando il suo account PayPal se ne ha gi\u00e0 uno.<\/li>\n \t<li>Creando un nuovo account Paypal e abbinandovi una carta di credito.<\/li>\n \t<li>Senza creare un account Paypal ed inserendo i dati della carta di credito direttamente nella maschera che appare a video dopo aver selezionato l\u2019opzione di pagamento PayPal.<\/li>\n<\/ul>\n<strong>In questo caso non sar\u00e0 richiesto il codice 3D Secure per convalidare la transazione.<\/strong>\n\nPer richiedere assistenza compila il form nella pagina CONTATTI specificando nell\u2019oggetto: Problema pagamento ordine ID(numero ordine), risponderemo il prima possibile. Con 3D Secure si definiscono i sistemi di protezione anti frode Verified by Visa e SecureCode MasterCard studiati per garantirle maggiore sicurezza nei pagamenti online.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La nostra politica sui pagamenti\u200b Accettiamo pagamenti tramite PayPal (circuiti supportati: account Paypal, Visa, Visa Electron, Mastercard, Maestro, American Express, Discover e Carta Aura), carte di credito, Addebito SEPA, Apple Pay e Google Pay, tramite la piattaforma per pagamenti elettronici STRIPE. In caso di pagamento con Addebito SEPA potrebbero essere previsti di costi di gestione [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-homepage.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-55899","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/pages\/55899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/comments?post=55899"}],"version-history":[{"count":0,"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/pages\/55899\/revisions"}],"wp:attachment":[{"href":"https:\/\/bo2.x-brain.it\/it\/wp-json\/wp\/v2\/media?parent=55899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}